{"id":9697,"date":"2014-12-16T15:51:04","date_gmt":"2014-12-16T20:51:04","guid":{"rendered":"http:\/\/debslunch.com\/debslunchblog\/?p=9697"},"modified":"2014-12-16T21:03:21","modified_gmt":"2014-12-17T02:03:21","slug":"belated-cookie-party-review","status":"publish","type":"post","link":"https:\/\/debslunch.com\/debslunchblog\/belated-cookie-party-review\/","title":{"rendered":"Cookie Party Platters"},"content":{"rendered":"<p>Here&#8217;re the pics for now &#8211; more Real Soon Now\u2122<\/p>\n<script>\/* <![CDATA[ *\/ portfolio_slideshow.slideshows[729] = {\"timeout\":\"\",\"autoplay\":\"false\",\"trans\":\"fade\",\"loop\":1,\"speed\":\"\",\"nowrap\":1}; \/* ]]> *\/<\/script><div id=\"slideshow-wrapper729\" class=\"slideshow-wrapper clearfix portfolio-slideshow-centered\">\n<div id=\"slideshow-nav729\" class=\"slideshow-nav\">\n\t<a class=\"pause\" style=\"display:none\" href=\"javascript:void(0);\">Pause<\/a>\n\t<a class=\"play\" href=\"javascript:void(0);\">Play<\/a>\n\t<a class=\"restart\" style=\"display:none\" href=\"javascript: void(0);\">Play<\/a>\n\t<a class=\"slideshow-prev\" href=\"javascript: void(0);\">Prev<\/a>\n\t<span class=\"sep\">|<\/span>\n\t<a class=\"slideshow-next\" href=\"javascript: void(0);\">Next<\/a>\n\t<span class=\"slideshow-info729 slideshow-info\"><\/span>\n<\/div><!-- .slideshow-nav -->\n<div class=\"pscarousel\">\n\t<div id=\"pager729\" class=\"pager items clearfix\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue4-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue4-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue3-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue3-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray7-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray7-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue2-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue2-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringues-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringues-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringues-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray6-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray6-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5R-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5R-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5R-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray3-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray3-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2R-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2R-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2R-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray1-150x150.jpg 150w, https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray1-144x144.jpg 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t<\/div>\n<\/div>\n<div id=\"portfolio-slideshow729\" class=\"portfolio-slideshow\" style=\"\">\n\n\t\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content \">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue4-400x266.jpg\" src=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue4-400x266.jpg\" height=\"266\" width=\"400\" alt=\"Slide 1\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue3-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 2\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray7-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 3\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringue2-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 4\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/meringues-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 5\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray6-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 6\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5R-400x180.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"180\" width=\"400\" alt=\"Slide 7\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray5-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 8\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray3-400x214.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"214\" width=\"400\" alt=\"Slide 9\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2R-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 10\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray2-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 11\"><\/a>\t\t<\/div>\n\n\t\n\t\t\t\t\n\t\t\t\n\t\t<div class=\"slideshow-next slideshow-content not-first\">\n\t\t<a class=\"slideshow-next\" href=\"javascript:void(0)\" ><img loading=\"lazy\" decoding=\"async\" class=\"psp-active\" data-img=\"https:\/\/debslunch.com\/debslunchblog\/wp-content\/uploads\/2014\/12\/tray1-400x266.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" height=\"266\" width=\"400\" alt=\"Slide 12\"><\/a>\t\t<\/div>\n\n\t<\/div><\/div><!--#slideshow-wrapper-->\n","protected":false},"excerpt":{"rendered":"<p>Here&#8217;re the pics for now &#8211; more Real Soon Now\u2122<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[169],"class_list":["post-9697","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-cookie-season"],"_links":{"self":[{"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/posts\/9697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/comments?post=9697"}],"version-history":[{"count":2,"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/posts\/9697\/revisions"}],"predecessor-version":[{"id":9711,"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/posts\/9697\/revisions\/9711"}],"wp:attachment":[{"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/media?parent=9697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/categories?post=9697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/debslunch.com\/debslunchblog\/wp-json\/wp\/v2\/tags?post=9697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}